{"id":471,"date":"2025-06-13T13:29:40","date_gmt":"2025-06-13T13:29:40","guid":{"rendered":"https:\/\/toumodi.net\/?p=471"},"modified":"2025-06-13T13:29:45","modified_gmt":"2025-06-13T13:29:45","slug":"la-cote-divoire-ouvre-son-premier-centre-de-formation-par-apprentissage-pour-les-metiers-du-batiment","status":"publish","type":"post","link":"https:\/\/toumodi.net\/index.php\/2025\/06\/13\/la-cote-divoire-ouvre-son-premier-centre-de-formation-par-apprentissage-pour-les-metiers-du-batiment\/","title":{"rendered":"La C\u00f4te d\u2019Ivoire ouvre son premier centre de formation par apprentissage pour les m\u00e9tiers du b\u00e2timent"},"content":{"rendered":"<div id=\"pl-471\"  class=\"panel-layout\" ><div id=\"pg-471-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-471-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-471-0-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"textwidget\"><p>Le Premier ministre, Robert Beugr\u00e9 Mamb\u00e9, a proc\u00e9d\u00e9 le jeudi 12 juin 2025, \u00e0 l\u2019inauguration officielle du Centre de formation par apprentissage aux m\u00e9tiers du b\u00e2timent, situ\u00e9 au sein du lyc\u00e9e professionnel commercial de Yopougon.<\/p>\n<p>Le ministre de l\u2019Enseignement technique, de la Formation professionnelle et de l\u2019Apprentissage, Koffi N\u2019Guessan, a pr\u00e9cis\u00e9 que ce centre vise \u00e0 offrir une seconde chance de formation \u00e0 celles et ceux rencontrant des difficult\u00e9s d\u2019insertion, tout en leur permettant d\u2019acqu\u00e9rir des comp\u00e9tences solides, en ad\u00e9quation avec les besoins du secteur du B\u00e2timent et des travaux publics (BTP) et leurs aspirations entrepreneuriales.<\/p>\n<p>Il a soulign\u00e9 que les formations dispens\u00e9es au sein de ce centre se feront selon le principe de l\u2019alternance sous statut scolaire. Concr\u00e8tement, chaque apprenant sera \u00e0 la fois \u00e9l\u00e8ve au centre de formation et apprenti au sein d\u2019une entreprise, alternant ainsi semaines en entreprise et semaines en classe, sur une p\u00e9riode de neuf mois.<\/p>\n<p>Ce centre accueillera des apprenants \u00e2g\u00e9s de 16 \u00e0 40 ans et proposera des formations dans dix m\u00e9tiers cl\u00e9s du b\u00e2timent \u00e0 savoir la ma\u00e7onnerie, carrelage, installation sanitaire, ferraillage, menuiserie-charpente, peinture b\u00e2timent, \u00e9lectricit\u00e9 b\u00e2timent, coffrage, installation en froid et climatisation, ainsi que pose de cloisons (plaquiste).<\/p>\n<p>Le ministre Koffi N\u2019Guessan a indiqu\u00e9 que les apprenants seront r\u00e9partis en classes de 25, et que les meilleurs d\u2019entre eux auront l\u2019opportunit\u00e9 de poursuivre leur formation \u00e0 Bordeaux et \u00e0 Nantes, en France. Certains pourront m\u00eame, \u00e0 terme, revenir comme formateurs \u00e0 Yopougon ou dans les futurs centres du pays.<\/p>\n<p>\u00c0 l\u2019issue de la formation, les participants se verront d\u00e9livrer un Certificat de qualification professionnelle (CQP), leur ouvrant les portes du march\u00e9 du travail ou leur permettant de r\u00e9int\u00e9grer le syst\u00e8me de formation professionnelle via les coll\u00e8ges d\u2019enseignement technique, les lyc\u00e9es professionnels, voire d\u2019acc\u00e9der \u00e0 des dipl\u00f4mes sup\u00e9rieurs tels que le Brevet de Technicien (BT), le Brevet de technicien sup\u00e9rieur (BTS), et m\u00eame au cycle d\u2019ing\u00e9nieur dans leur sp\u00e9cialit\u00e9.<\/p>\n<figure id=\"attachment_205915\" class=\"wp-caption alignleft\" aria-describedby=\"caption-attachment-205915\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-205915\" src=\"https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-300x200.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-300x200.jpg 300w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-1024x683.jpg 1024w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-768x512.jpg 768w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-1536x1024.jpg 1536w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-2048x1365.jpg 2048w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-150x100.jpg 150w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-450x300.jpg 450w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-1200x800.jpg 1200w, https:\/\/www.aip.ci\/wp-content\/uploads\/2025\/06\/Inauguration-CeFA-Yop-12-juin-2025-85-1320x880.jpg 1320w\" alt=\"\" width=\"300\" height=\"200\" \/><figcaption id=\"caption-attachment-205915\" class=\"wp-caption-text\">Les apprenants sont heureux de ce grand projet<\/figcaption><\/figure>\n<p>Le Premier ministre s\u2019est f\u00e9licit\u00e9 de ce programme structurant qu\u2019il consid\u00e8re comme un puissant levier pour fournir aux entreprises du secteur une main-d\u2019\u0153uvre locale, comp\u00e9tente et qualifi\u00e9e, capable d\u2019accompagner le vaste programme de construction de logements initi\u00e9 par le gouvernement.<\/p>\n<p>M. Mamb\u00e9 a \u00e9galement recommand\u00e9 que la sp\u00e9cialit\u00e9 de topographie soit ajout\u00e9e au cursus, soulignant son importance pour la pr\u00e9cision dans la construction. Il a insist\u00e9 sur la n\u00e9cessit\u00e9 d\u2019enseigner aux apprenants \u00e0 bien positionner le ferraillage, \u00e0 ma\u00eetriser les dosages de b\u00e9ton et \u00e0 respecter les normes en mati\u00e8re d\u2019\u00e9lectricit\u00e9, afin de pr\u00e9venir tout risque de court-circuit ou d\u2019incendie.<\/p>\n<p>Le chef du gouvernement a exhort\u00e9 les jeunes, ainsi que les professionnels du secteur du b\u00e2timent, \u00e0 s\u2019approprier cet outil de formation, v\u00e9ritable tremplin pour devenir des experts dans des domaines aussi essentiels que la menuiserie, la plomberie, la climatisation, la ma\u00e7onnerie et l\u2019\u00e9lectricit\u00e9.<\/p>\n<p>(AIP)<\/p>\n<p>bsp\/cmas<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Le Premier ministre, Robert Beugr\u00e9 Mamb\u00e9, a proc\u00e9d\u00e9 le jeudi 12 juin 2025, \u00e0 l\u2019inauguration officielle du Centre de formation par apprentissage aux m\u00e9tiers du b\u00e2timent, situ\u00e9 au sein du&hellip; <\/p>\n","protected":false},"author":1,"featured_media":472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/comments?post=471"}],"version-history":[{"count":1,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/471\/revisions"}],"predecessor-version":[{"id":473,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/471\/revisions\/473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media\/472"}],"wp:attachment":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media?parent=471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/categories?post=471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/tags?post=471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}