{"id":703,"date":"2025-09-18T16:37:04","date_gmt":"2025-09-18T16:37:04","guid":{"rendered":"https:\/\/toumodi.net\/?p=703"},"modified":"2025-09-18T16:37:05","modified_gmt":"2025-09-18T16:37:05","slug":"presidentielle-2025-la-ministre-gouverneure-raymonde-goudou-exhorte-les-jeunes-de-toumodi-a-preserver-la-paix","status":"publish","type":"post","link":"https:\/\/toumodi.net\/index.php\/2025\/09\/18\/presidentielle-2025-la-ministre-gouverneure-raymonde-goudou-exhorte-les-jeunes-de-toumodi-a-preserver-la-paix\/","title":{"rendered":"Pr\u00e9sidentielle 2025: la ministre-gouverneure Raymonde Goudou exhorte les jeunes de Toumodi \u00e0 pr\u00e9server la paix"},"content":{"rendered":"<div id=\"pl-703\"  class=\"panel-layout\" ><div id=\"pg-703-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-703-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-703-0-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"textwidget\"><p data-start=\"266\" data-end=\"513\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-701 alignleft\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/09\/Raymonde-goudou-300x217.jpg\" alt=\"\" width=\"300\" height=\"217\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/09\/Raymonde-goudou-300x217.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/09\/Raymonde-goudou-768x554.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/09\/Raymonde-goudou.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>La ministre-gouverneure du district autonome des Lacs, Dr Raymonde Goudou, a invit\u00e9 les jeunes de Toumodi \u00e0 \u0153uvrer pour la paix et la coh\u00e9sion sociale \u00e0 l\u2019approche de l\u2019\u00e9lection pr\u00e9sidentielle d\u2019octobre 2025.<\/p>\n<p data-start=\"515\" data-end=\"701\">Elle a lanc\u00e9 cet appel le mardi 16 septembre, en marge de la c\u00e9r\u00e9monie de remise d\u2019attestations de fin de stage d\u2019immersion aux \u00e9l\u00e8ves et \u00e9tudiants, organis\u00e9e par l\u2019Agence emploi jeunes.<\/p>\n<p data-start=\"703\" data-end=\"988\">Dr Goudou a soulign\u00e9 que la tenue de cette c\u00e9r\u00e9monie a \u00e9t\u00e9 rendue possible gr\u00e2ce au climat de paix et de s\u00e9curit\u00e9 qui pr\u00e9vaut actuellement en C\u00f4te d\u2019Ivoire. Elle a exhort\u00e9 les jeunes \u00e0 pr\u00e9server cet acquis en se posant en \u00ab ambassadeurs de la paix et de la coh\u00e9sion sociale \u00bb.<\/p>\n<p data-start=\"990\" data-end=\"1275\">\u00ab Ne c\u00e9dez pas \u00e0 la manipulation ni \u00e0 la violence \u00e0 l\u2019approche des \u00e9lections. Soyez plut\u00f4t des artisans de paix, des b\u00e2tisseurs de la fraternit\u00e9 et des d\u00e9fenseurs du vivre-ensemble \u00bb, a-t-elle insist\u00e9, appelant la jeunesse \u00e0 placer l\u2019int\u00e9r\u00eat sup\u00e9rieur de la nation au-dessus de tout.<\/p>\n<p data-start=\"1277\" data-end=\"1678\">Dans le m\u00eame esprit, le d\u00e9l\u00e9gu\u00e9 r\u00e9gional du Conseil national des jeunes de C\u00f4te d\u2019Ivoire (CNJCI), Kouakou Julien, a rappel\u00e9 que les \u00e9lections constituent un moment d\u2019expression d\u00e9mocratique. Il a encourag\u00e9 les jeunes \u00e0 en faire un levier de d\u00e9veloppement local et national, r\u00e9affirmant l\u2019attachement du CNJCI aux valeurs du travail, de l\u2019entraide et de la solidarit\u00e9 pour une C\u00f4te d\u2019Ivoire prosp\u00e8re.<\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La ministre-gouverneure du district autonome des Lacs, Dr Raymonde Goudou, a invit\u00e9 les jeunes de Toumodi \u00e0 \u0153uvrer pour la paix et la coh\u00e9sion sociale \u00e0 l\u2019approche de l\u2019\u00e9lection pr\u00e9sidentielle&hellip; <\/p>\n","protected":false},"author":1,"featured_media":701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/comments?post=703"}],"version-history":[{"count":1,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/703\/revisions"}],"predecessor-version":[{"id":704,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/703\/revisions\/704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media?parent=703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/categories?post=703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/tags?post=703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}