{"id":939,"date":"2025-12-24T10:28:26","date_gmt":"2025-12-24T10:28:26","guid":{"rendered":"https:\/\/toumodi.net\/?p=939"},"modified":"2025-12-24T10:37:25","modified_gmt":"2025-12-24T10:37:25","slug":"toumodi-une-activite-de-sensibilisation-des-jeunes-filles-sur-les-grossesses-en-milieu-scolaire-au-college-moderne-dabli","status":"publish","type":"post","link":"https:\/\/toumodi.net\/index.php\/2025\/12\/24\/toumodi-une-activite-de-sensibilisation-des-jeunes-filles-sur-les-grossesses-en-milieu-scolaire-au-college-moderne-dabli\/","title":{"rendered":"Toumodi : une activit\u00e9 de sensibilisation des jeunes filles sur les grossesses en milieu scolaire au Coll\u00e8ge Moderne d\u2019Abli"},"content":{"rendered":"<div id=\"pl-939\"  class=\"panel-layout\" ><div id=\"pg-939-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-939-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-939-0-0-0\" class=\"so-panel widget widget_black-studio-tinymce widget_black_studio_tinymce panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"textwidget\"><p data-start=\"467\" data-end=\"987\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-941 alignleft\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-81-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le <strong data-start=\"470\" data-end=\"485\">19 d\u00e9cembre<\/strong>, le <strong data-start=\"490\" data-end=\"516\">Coll\u00e8ge Moderne d\u2019Abli<\/strong>, dans la commune de <strong data-start=\"537\" data-end=\"548\">Toumodi<\/strong>, a accueilli une importante <strong data-start=\"577\" data-end=\"664\">activit\u00e9 de sensibilisation des jeunes filles sur les grossesses en milieu scolaire<\/strong>.<br data-start=\"665\" data-end=\"668\" \/>Cette action a \u00e9t\u00e9 <strong data-start=\"687\" data-end=\"785\">coorganis\u00e9e par le Rotaract Club Abidjan Elixir et la Fondation Agissons Ensemble pour Toumodi<\/strong>, dans le cadre du <strong data-start=\"804\" data-end=\"819\">projet AIP4<\/strong>, <strong data-start=\"821\" data-end=\"875\">en pr\u00e9sence du principal du Coll\u00e8ge Moderne d\u2019Abli<\/strong>, t\u00e9moignant de l\u2019engagement de l\u2019administration scolaire en faveur de la protection et du bien-\u00eatre des \u00e9l\u00e8ves.<\/p>\n<p data-start=\"1060\" data-end=\"1465\">La <strong data-start=\"1063\" data-end=\"1107\">Fondation Agissons Ensemble pour Toumodi<\/strong>, dirig\u00e9e par <strong data-start=\"1121\" data-end=\"1136\">AKA Vianney<\/strong>, <strong data-start=\"1138\" data-end=\"1167\">fils d\u2019Abli et de Toumodi<\/strong>, s\u2019investit activement dans les actions sociales, \u00e9ducatives et communautaires au profit des populations locales.<br data-start=\"1281\" data-end=\"1284\" \/>En collaboration avec le <strong data-start=\"1309\" data-end=\"1341\">Rotaract Club Abidjan Elixir<\/strong>, cette initiative vise \u00e0 <strong data-start=\"1367\" data-end=\"1464\">apporter des r\u00e9ponses concr\u00e8tes \u00e0 la probl\u00e9matique des grossesses pr\u00e9coces en milieu scolaire<\/strong>.<\/p>\n<p data-start=\"1539\" data-end=\"1635\">Cette journ\u00e9e de sensibilisation a \u00e9t\u00e9 marqu\u00e9e par plusieurs activit\u00e9s essentielles, notamment :<\/p>\n<ul data-start=\"1637\" data-end=\"1969\">\n<li data-start=\"1637\" data-end=\"1741\">\n<p data-start=\"1639\" data-end=\"1741\">des <strong data-start=\"1643\" data-end=\"1703\">\u00e9changes \u00e9ducatifs sur les grossesses en milieu scolaire<\/strong>, leurs causes et leurs cons\u00e9quences ;<\/p>\n<\/li>\n<li data-start=\"1742\" data-end=\"1846\">\n<p data-start=\"1744\" data-end=\"1846\">une <strong data-start=\"1748\" data-end=\"1791\">sensibilisation \u00e0 l\u2019hygi\u00e8ne menstruelle<\/strong>, afin de renforcer l\u2019information et lever les tabous ;<\/p>\n<\/li>\n<li data-start=\"1847\" data-end=\"1969\">\n<p data-start=\"1849\" data-end=\"1969\">le <strong data-start=\"1852\" data-end=\"1889\">partage de serviettes hygi\u00e9niques<\/strong> au profit des \u00e9l\u00e8ves, pour favoriser leur assiduit\u00e9 et leur maintien \u00e0 l\u2019\u00e9cole.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1971\" data-end=\"2094\">Ces actions contribuent \u00e0 <strong data-start=\"1997\" data-end=\"2032\">pr\u00e9venir le d\u00e9crochage scolaire<\/strong> et \u00e0 renforcer la confiance et l\u2019autonomie des jeunes filles.<\/p>\n<p data-start=\"2161\" data-end=\"2436\">La pr\u00e9sence du <strong data-start=\"2176\" data-end=\"2215\">principal du Coll\u00e8ge Moderne d\u2019Abli<\/strong>, aux c\u00f4t\u00e9s des organisateurs et des acteurs locaux, a donn\u00e9 un caract\u00e8re institutionnel fort \u00e0 cette activit\u00e9, illustrant l\u2019importance accord\u00e9e \u00e0 <strong data-start=\"2362\" data-end=\"2435\">l\u2019\u00e9ducation, \u00e0 la sant\u00e9 scolaire et \u00e0 la protection de la jeune fille<\/strong>.<\/p>\n<p data-start=\"2438\" data-end=\"2618\"><strong data-start=\"2438\" data-end=\"2453\">Toumodi.net<\/strong>, \u00e0 travers son <strong data-start=\"2469\" data-end=\"2496\">reporter sur le terrain<\/strong>, a assur\u00e9 la couverture m\u00e9diatique de cette initiative, fid\u00e8le \u00e0 sa mission de <strong data-start=\"2576\" data-end=\"2617\">m\u00e9dia local impartial et de proximit\u00e9<\/strong>.<\/p>\n<p data-start=\"2683\" data-end=\"2906\">\u00c0 travers cette activit\u00e9, les organisateurs d\u00e9montrent que <strong data-start=\"2742\" data-end=\"2808\">la sensibilisation, l\u2019\u00e9ducation et la solidarit\u00e9 communautaire<\/strong> sont des leviers essentiels pour construire un avenir meilleur pour les jeunes filles de Toumodi.<\/p>\n<p data-start=\"2908\" data-end=\"3102\"><strong data-start=\"2911\" data-end=\"2926\">Toumodi.net<\/strong> salue et encourage toutes les initiatives qui \u0153uvrent pour <strong data-start=\"2986\" data-end=\"3048\">la protection, l\u2019\u00e9panouissement et l\u2019avenir de la jeunesse<\/strong>, en particulier des jeunes filles en milieu scolaire.<\/p>\n<p data-start=\"3104\" data-end=\"3170\"><strong data-start=\"3107\" data-end=\"3170\">Toumodi avance, quand la jeunesse est prot\u00e9g\u00e9e et inform\u00e9e.<\/strong><\/p>\n<p data-start=\"3104\" data-end=\"3170\"><strong data-start=\"3107\" data-end=\"3170\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-943\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-300x225.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-1024x768.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-768x576.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-1536x1152.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-1-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-944\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-300x225.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-1024x768.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-768x576.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-1536x1152.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-5-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-945\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-300x225.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-1024x768.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-768x576.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-1536x1152.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-7-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-946\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-300x225.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-1024x768.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-768x576.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-1536x1152.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-21-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-947\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-29-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-948\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-30-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-949\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-32-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-952\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-44-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-953\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-50-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-954\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-72-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-955\" src=\"http:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-300x226.jpg 300w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-1024x771.jpg 1024w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-768x578.jpg 768w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-1536x1157.jpg 1536w, https:\/\/toumodi.net\/wp-content\/uploads\/2025\/12\/Sensibilation-college-moderne-Abli-75-2048x1542.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Le 19 d\u00e9cembre, le Coll\u00e8ge Moderne d\u2019Abli, dans la commune de Toumodi, a accueilli une importante activit\u00e9 de sensibilisation des jeunes filles sur les grossesses en milieu scolaire.Cette action a&hellip; <\/p>\n","protected":false},"author":1,"featured_media":956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/comments?post=939"}],"version-history":[{"count":3,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/939\/revisions"}],"predecessor-version":[{"id":959,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/posts\/939\/revisions\/959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media\/956"}],"wp:attachment":[{"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/media?parent=939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/categories?post=939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toumodi.net\/index.php\/wp-json\/wp\/v2\/tags?post=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}